{"id":4951,"date":"2022-08-26T21:44:19","date_gmt":"2022-08-26T21:44:19","guid":{"rendered":"https:\/\/highlifeng.com\/yoruba\/?p=4951"},"modified":"2022-08-26T21:44:19","modified_gmt":"2022-08-26T21:44:19","slug":"adewale-ayuba-koloba-koloba","status":"publish","type":"post","link":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/","title":{"rendered":"Adewale Ayuba &#8211; Koloba Koloba"},"content":{"rendered":"<p><strong><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4962\" src=\"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?resize=696%2C392&#038;ssl=1\" width=\"696\" height=\"392\" alt=\"Adewale Ayuba - Koloba Koloba\" title=\"Adewale Ayuba - Koloba Koloba\" srcset=\"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/>Cardozo Organization<\/strong> presents <strong>Adewale Ayuba<\/strong><strong>\u00a0<\/strong>in this in this Yoruba fuji music titled <strong> Koloba Koloba<\/strong><em>\u00a0<\/em>for free download.<\/p>\n<p>Download all old and latest new songs by <strong>Adewale Ayuba &#8211; Koloba Koloba\u00a0<\/strong>in audio mp3 fromat below:<\/p>\n<p style=\"text-align: center\"><iframe loading=\"lazy\" class=\"lscp_exclude\" style=\"border:none;\" id=\"hlplayer\" width=\"100%\" height=\"200\" src=\"https:\/\/highlifeng.com\/player\/embed\/?url=https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/&post_title=Adewale Ayuba &#8211; Koloba Koloba&image=https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1&song=http:\/\/cdn2.highlifeng.com.ng\/yoruba\/files\/Koloba_Koloba-Adewale_Ayuba.mp3&title=&artist=Adewale Ayuba &#8211; Koloba Koloba&hljs\"><\/iframe><div class=\"download-btn-wrapper hl-download-box\"><!-- LINK 1 -->\n<div class=\"link-label link1\">\n  <div class=\"link-badge link1\">\ud83d\udd17 LINK 1<\/div>\n<\/div><a class=\"download-btn-card download-btn-black\" rel=\"nofollow\" href=\"https:\/\/makossabase.com\/proceed\/?id=4951&#038;title=Adewale%20Ayuba%20%26%238211%3B%20Koloba%20Koloba&#038;img=aHR0cHM6Ly9pMC53cC5jb20vaGlnaGxpZmVuZy5jb20veW9ydWJhL3dwLWNvbnRlbnQvdXBsb2Fkcy8yMDIyLzA4L0hpZ2hsaWZlbmcuY29tXy04Ny53ZWJwP2ZpdD0xMjgwJTJDNzIwJnNzbD0x&#038;url=aHR0cDovL2NkbjIuaGlnaGxpZmVuZy5jb20ubmcveW9ydWJhL2ZpbGVzL0tvbG9iYV9Lb2xvYmEtQWRld2FsZV9BeXViYS5tcDM=&#038;btn=l1&#038;from=https:\/\/highlifeng.com\/yoruba\" target=\"_blank\" data-popup-exclude><span class=\"download-btn-left\"><span class=\"icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M144 480C64.5 480 0 415.5 0 336c0-62.8 40.2-116.2 96.2-135.9c-.1-2.7-.2-5.4-.2-8.1c0-88.4 71.6-160 160-160c59.3 0 111 32.2 138.7 80.2C409.9 102 428.3 96 448 96c53 0 96 43 96 96c0 12.2-2.3 23.8-6.4 34.6C596 238.4 640 290.1 640 352c0 70.7-57.3 128-128 128l-368 0zm79-167l80 80c9.4 9.4 24.6 9.4 33.9 0l80-80c9.4-9.4 9.4-24.6 0-33.9s-24.6-9.4-33.9 0l-39 39L344 184c0-13.3-10.7-24-24-24s-24 10.7-24 24l0 134.1-39-39c-9.4-9.4-24.6-9.4-33.9 0s-9.4 24.6 0 33.9z\"\/><\/svg><\/span><span class=\"download-btn-divider\"><\/span><span class=\"download-btn-content\">DOWNLOAD MP3: Adewale Ayuba &#8211; Koloba Koloba<\/span><\/span><span class=\"download-btn\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M256 464a208 208 0 1 1 0-416 208 208 0 1 1 0 416zM256 0a256 256 0 1 0 0 512A256 256 0 1 0 256 0zM376.9 294.6c4.5-4.2 7.1-10.1 7.1-16.3c0-12.3-10-22.3-22.3-22.3L304 256l0-96c0-17.7-14.3-32-32-32l-32 0c-17.7 0-32 14.3-32 32l0 96-57.7 0C138 256 128 266 128 278.3c0 6.2 2.6 12.1 7.1 16.3l107.1 99.9c3.8 3.5 8.7 5.5 13.8 5.5s10.1-2 13.8-5.5l107.1-99.9z\"\/><\/svg><\/span><\/a> <!-- LINK 2 -->\n<div class=\"link-label link2\">\n  <div class=\"link-badge link2\">\ud83d\udd17 LINK 2<\/div>\n<\/div><a class=\"download-btn-card download-btn-red\" rel=\"nofollow\" href=\"https:\/\/makossabase.com\/proceed\/?id=4951&#038;title=Adewale%20Ayuba%20%26%238211%3B%20Koloba%20Koloba&#038;img=aHR0cHM6Ly9pMC53cC5jb20vaGlnaGxpZmVuZy5jb20veW9ydWJhL3dwLWNvbnRlbnQvdXBsb2Fkcy8yMDIyLzA4L0hpZ2hsaWZlbmcuY29tXy04Ny53ZWJwP2ZpdD0xMjgwJTJDNzIwJnNzbD0x&#038;url=aHR0cDovL2NkbjIuaGlnaGxpZmVuZy5jb20ubmcveW9ydWJhL2ZpbGVzL0tvbG9iYV9Lb2xvYmEtQWRld2FsZV9BeXViYS5tcDM=&#038;btn=l2&#038;from=https:\/\/highlifeng.com\/yoruba\" target=\"_blank\" data-popup-exclude><span class=\"download-btn-left\"><span class=\"icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M144 480C64.5 480 0 415.5 0 336c0-62.8 40.2-116.2 96.2-135.9c-.1-2.7-.2-5.4-.2-8.1c0-88.4 71.6-160 160-160c59.3 0 111 32.2 138.7 80.2C409.9 102 428.3 96 448 96c53 0 96 43 96 96c0 12.2-2.3 23.8-6.4 34.6C596 238.4 640 290.1 640 352c0 70.7-57.3 128-128 128l-368 0zm79-167l80 80c9.4 9.4 24.6 9.4 33.9 0l80-80c9.4-9.4 9.4-24.6 0-33.9s-24.6-9.4-33.9 0l-39 39L344 184c0-13.3-10.7-24-24-24s-24 10.7-24 24l0 134.1-39-39c-9.4-9.4-24.6-9.4-33.9 0s-9.4 24.6 0 33.9z\"\/><\/svg><\/span><span class=\"download-btn-divider\"><\/span><span class=\"download-btn-content\">DOWNLOAD MP3: Adewale Ayuba &#8211; Koloba Koloba<\/span><\/span><span class=\"download-btn\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M256 464a208 208 0 1 1 0-416 208 208 0 1 1 0 416zM256 0a256 256 0 1 0 0 512A256 256 0 1 0 256 0zM376.9 294.6c4.5-4.2 7.1-10.1 7.1-16.3c0-12.3-10-22.3-22.3-22.3L304 256l0-96c0-17.7-14.3-32-32-32l-32 0c-17.7 0-32 14.3-32 32l0 96-57.7 0C138 256 128 266 128 278.3c0 6.2 2.6 12.1 7.1 16.3l107.1 99.9c3.8 3.5 8.7 5.5 13.8 5.5s10.1-2 13.8-5.5l107.1-99.9z\"\/><\/svg><\/span><\/a><div class=\"download-btn-notice\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M256 0c4.6 0 9.2 1 13.4 2.9L457.7 82.8c22 9.3 38.4 31 38.3 57.2c-.5 99.2-41.3 280.7-213.6 363.2c-16.7 8-36.1 8-52.8 0C57.3 420.7 16.5 239.2 16 140c-.1-26.2 16.3-47.9 38.3-57.2L242.7 2.9C246.8 1 251.4 0 256 0zm0 66.8l0 378.1C394 378 431.1 230.1 432 141.4L256 66.8s0 0 0 0z\"\/><\/svg><span>If one link fails, use the <span style=\"color:var(--main-color);\">alternate server<\/span> above.<\/span><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cardozo Organization presents Adewale Ayuba\u00a0in this in this Yoruba fuji music titled Koloba Koloba\u00a0for free download. Download all old and latest new songs by Adewale Ayuba &#8211; Koloba Koloba\u00a0in audio mp3 fromat below: \ud83d\udd17 LINK 1 DOWNLOAD MP3: Adewale Ayuba &#8211; Koloba Koloba \ud83d\udd17 LINK 2 DOWNLOAD MP3: Adewale Ayuba &#8211; Koloba KolobaIf one link [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":4962,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[3351],"class_list":["post-4951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-yoruba-fuji-music","tag-adewale-ayuba"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adewale Ayuba - Koloba Koloba | Mp3 Download<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adewale Ayuba - Koloba Koloba | Mp3 Download\" \/>\n<meta property=\"og:description\" content=\"Cardozo Organization presents Adewale Ayuba\u00a0in this in this Yoruba fuji music titled Koloba Koloba\u00a0for free download. Download all old and latest new songs by Adewale Ayuba &#8211; Koloba Koloba\u00a0in audio mp3 fromat below: \ud83d\udd17 LINK 1 DOWNLOAD MP3: Adewale Ayuba &#8211; Koloba Koloba \ud83d\udd17 LINK 2 DOWNLOAD MP3: Adewale Ayuba &#8211; Koloba KolobaIf one link [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/\" \/>\n<meta property=\"og:site_name\" content=\"HighlifeNg\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-26T21:44:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CubansMoney\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CubansMoney\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/\"},\"author\":{\"name\":\"CubansMoney\",\"@id\":\"https:\/\/highlifeng.com\/yoruba\/#\/schema\/person\/416030e41bb74c8585c4d908c4b098f9\"},\"headline\":\"Adewale Ayuba &#8211; Koloba Koloba\",\"datePublished\":\"2022-08-26T21:44:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/\"},\"wordCount\":59,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1\",\"keywords\":[\"Adewale Ayuba\"],\"articleSection\":[\"Fuji Music\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/\",\"url\":\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/\",\"name\":\"Adewale Ayuba - Koloba Koloba | Mp3 Download\",\"isPartOf\":{\"@id\":\"https:\/\/highlifeng.com\/yoruba\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1\",\"datePublished\":\"2022-08-26T21:44:19+00:00\",\"author\":{\"@id\":\"https:\/\/highlifeng.com\/yoruba\/#\/schema\/person\/416030e41bb74c8585c4d908c4b098f9\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1\",\"width\":1280,\"height\":720,\"caption\":\"Adewale Ayuba - Koloba Koloba\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/highlifeng.com\/yoruba\/#website\",\"url\":\"https:\/\/highlifeng.com\/yoruba\/\",\"name\":\"HighlifeNg\",\"description\":\"Download Latest Yoruba Nigeria Music | Mp3 Songs &amp; DJ Mixtapes 2025\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/highlifeng.com\/yoruba\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/highlifeng.com\/yoruba\/#\/schema\/person\/416030e41bb74c8585c4d908c4b098f9\",\"name\":\"CubansMoney\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/highlifeng.com\/yoruba\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ef2226331a260a5521e27774289fec11201aa91824c5bc3418b4cb7a14c86388?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ef2226331a260a5521e27774289fec11201aa91824c5bc3418b4cb7a14c86388?s=96&d=mm&r=g\",\"caption\":\"CubansMoney\"},\"sameAs\":[\"https:\/\/highlifeng.com\"],\"url\":\"https:\/\/highlifeng.com\/yoruba\/author\/neche\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adewale Ayuba - Koloba Koloba | Mp3 Download","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/","og_locale":"en_US","og_type":"article","og_title":"Adewale Ayuba - Koloba Koloba | Mp3 Download","og_description":"Cardozo Organization presents Adewale Ayuba\u00a0in this in this Yoruba fuji music titled Koloba Koloba\u00a0for free download. Download all old and latest new songs by Adewale Ayuba &#8211; Koloba Koloba\u00a0in audio mp3 fromat below: \ud83d\udd17 LINK 1 DOWNLOAD MP3: Adewale Ayuba &#8211; Koloba Koloba \ud83d\udd17 LINK 2 DOWNLOAD MP3: Adewale Ayuba &#8211; Koloba KolobaIf one link [&hellip;]","og_url":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/","og_site_name":"HighlifeNg","article_published_time":"2022-08-26T21:44:19+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1","type":"image\/jpeg"}],"author":"CubansMoney","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CubansMoney","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#article","isPartOf":{"@id":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/"},"author":{"name":"CubansMoney","@id":"https:\/\/highlifeng.com\/yoruba\/#\/schema\/person\/416030e41bb74c8585c4d908c4b098f9"},"headline":"Adewale Ayuba &#8211; Koloba Koloba","datePublished":"2022-08-26T21:44:19+00:00","mainEntityOfPage":{"@id":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/"},"wordCount":59,"commentCount":0,"image":{"@id":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1","keywords":["Adewale Ayuba"],"articleSection":["Fuji Music"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/","url":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/","name":"Adewale Ayuba - Koloba Koloba | Mp3 Download","isPartOf":{"@id":"https:\/\/highlifeng.com\/yoruba\/#website"},"primaryImageOfPage":{"@id":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#primaryimage"},"image":{"@id":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1","datePublished":"2022-08-26T21:44:19+00:00","author":{"@id":"https:\/\/highlifeng.com\/yoruba\/#\/schema\/person\/416030e41bb74c8585c4d908c4b098f9"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-koloba-koloba\/#primaryimage","url":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1","contentUrl":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1","width":1280,"height":720,"caption":"Adewale Ayuba - Koloba Koloba"},{"@type":"WebSite","@id":"https:\/\/highlifeng.com\/yoruba\/#website","url":"https:\/\/highlifeng.com\/yoruba\/","name":"HighlifeNg","description":"Download Latest Yoruba Nigeria Music | Mp3 Songs &amp; DJ Mixtapes 2025","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/highlifeng.com\/yoruba\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/highlifeng.com\/yoruba\/#\/schema\/person\/416030e41bb74c8585c4d908c4b098f9","name":"CubansMoney","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/highlifeng.com\/yoruba\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ef2226331a260a5521e27774289fec11201aa91824c5bc3418b4cb7a14c86388?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ef2226331a260a5521e27774289fec11201aa91824c5bc3418b4cb7a14c86388?s=96&d=mm&r=g","caption":"CubansMoney"},"sameAs":["https:\/\/highlifeng.com"],"url":"https:\/\/highlifeng.com\/yoruba\/author\/neche\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-87.webp?fit=1280%2C720&ssl=1","jetpack-related-posts":[{"id":5028,"url":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-ijo-fuji-a\/","url_meta":{"origin":4951,"position":0},"title":"Adewale Ayuba &#8211; Ijo Fuji A","author":"CubansMoney","date":"August 27, 2022","format":false,"excerpt":"Cardozo Organization presents Adewale Ayuba\u00a0in this in this Yoruba fuji music titled \u00a0- Ijo Fuji\u00a0from the album Ijo Fuji\u00a0for free download. Download all old and latest new songs by Adewale Ayuba - Ijo Fuji in audio mp3 fromat below: PART 1 http:\/\/cdn2.highlifeng.com.ng\/yoruba\/files\/Ijo_Fuji_A-Adewale_Ayuba.mp3 DOWNLOAD MP3: Adewale Ayuba - Ijo Fuji 1\u2026","rel":"","context":"In &quot;Fuji Music&quot;","block_context":{"text":"Fuji Music","link":"https:\/\/highlifeng.com\/yoruba\/yoruba-fuji-music\/"},"img":{"alt_text":"Adewale Ayuba - Ijo Fuji A","src":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-105.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-105.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-105.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-105.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-105.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5066,"url":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-mellow\/","url_meta":{"origin":4951,"position":1},"title":"Adewale Ayuba &#8211; Mellow","author":"CubansMoney","date":"August 27, 2022","format":false,"excerpt":"Cardozo Organization presents Adewale Ayuba\u00a0in this in this Yoruba fuji music titled Mellow\u00a0from the album Mellow\u00a0for free download. Download all old and latest new songs by Adewale Ayuba - Mellow\u00a0in audio mp3 fromat below: PART 1 http:\/\/cdn2.highlifeng.com.ng\/yoruba\/files\/Mellow_Part_1-Adewale_Ayuba.mp3 DOWNLOAD MP3: Adewale Ayuba - Mellow 1 PART 2 http:\/\/cdn2.highlifeng.com.ng\/yoruba\/files\/Mellow_Part_2-Adewale_Ayuba.mp3 DOWNLOAD MP3: Adewale\u2026","rel":"","context":"In &quot;Fuji Music&quot;","block_context":{"text":"Fuji Music","link":"https:\/\/highlifeng.com\/yoruba\/yoruba-fuji-music\/"},"img":{"alt_text":"Adewale Ayuba - Mellow","src":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-117.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-117.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-117.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-117.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-117.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4952,"url":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-jekarira\/","url_meta":{"origin":4951,"position":2},"title":"Adewale Ayuba &#8211; Jekarira","author":"CubansMoney","date":"August 26, 2022","format":false,"excerpt":"Cardozo Organization presents Adewale Ayuba\u00a0in this in this Yoruba fuji music titled Jekarira\u00a0for free download. Download all old and latest new songs by Adewale Ayuba - Jekarira in audio mp3 fromat below: http:\/\/cdn2.highlifeng.com.ng\/yoruba\/files\/Jekarira-Adewale_Ayuba.mp3 DOWNLOAD MP3: Adewale Ayuba - Jekarira","rel":"","context":"In &quot;Fuji Music&quot;","block_context":{"text":"Fuji Music","link":"https:\/\/highlifeng.com\/yoruba\/yoruba-fuji-music\/"},"img":{"alt_text":"Adewale Ayuba - Jekarira","src":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-90.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-90.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-90.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-90.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-90.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5010,"url":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-acceleration\/","url_meta":{"origin":4951,"position":3},"title":"Adewale Ayuba &#8211; Acceleration","author":"CubansMoney","date":"August 27, 2022","format":false,"excerpt":"Cardozo Organization presents Adewale Ayuba\u00a0in this in this Yoruba fuji music titled Acceleration\u00a0from the album Acceleration for free download. Download all old and latest new songs by Adewale Ayuba - Acceleration\u00a0in audio mp3 fromat below: http:\/\/cdn2.highlifeng.com.ng\/yoruba\/files\/Acceleration-Adewale_Ayuba.mp3 DOWNLOAD MP3: Adewale Ayuba - Acceleration \u00a0","rel":"","context":"In &quot;Fuji Music&quot;","block_context":{"text":"Fuji Music","link":"https:\/\/highlifeng.com\/yoruba\/yoruba-fuji-music\/"},"img":{"alt_text":"Adewale Ayuba - Acceleration","src":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-100.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-100.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-100.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-100.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-100.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5011,"url":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-remember\/","url_meta":{"origin":4951,"position":4},"title":"Adewale Ayuba &#8211; Remember","author":"CubansMoney","date":"August 27, 2022","format":false,"excerpt":"Cardozo Organization presents Adewale Ayuba\u00a0in this in this Yoruba fuji music titled Remember from the album Acceleration for free download. Download all old and latest new songs by Adewale Ayuba - Remember\u00a0in audio mp3 fromat below: http:\/\/cdn2.highlifeng.com.ng\/yoruba\/files\/Remember-Adewale_Ayuba.mp3 DOWNLOAD MP3: Adewale Ayuba - Remember","rel":"","context":"In &quot;Fuji Music&quot;","block_context":{"text":"Fuji Music","link":"https:\/\/highlifeng.com\/yoruba\/yoruba-fuji-music\/"},"img":{"alt_text":"Adewale Ayuba - Remember","src":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-99.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-99.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-99.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-99.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-99.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5024,"url":"https:\/\/highlifeng.com\/yoruba\/adewale-ayuba-recognition\/","url_meta":{"origin":4951,"position":5},"title":"Adewale Ayuba &#8211; Recognition","author":"CubansMoney","date":"August 27, 2022","format":false,"excerpt":"Cardozo Organization presents Adewale Ayuba\u00a0in this in this Yoruba fuji music titled Recognition\u00a0from the album Acceleration for free download. Download all old and latest new songs by Adewale Ayuba - Recognition in audio mp3 fromat below: http:\/\/cdn2.highlifeng.com.ng\/yoruba\/files\/Recognition-Adewale_Ayuba.mp3 DOWNLOAD MP3: Adewale Ayuba - Recognition","rel":"","context":"In &quot;Fuji Music&quot;","block_context":{"text":"Fuji Music","link":"https:\/\/highlifeng.com\/yoruba\/yoruba-fuji-music\/"},"img":{"alt_text":"Adewale Ayuba - Acceleration","src":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-100.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-100.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-100.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-100.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/highlifeng.com\/yoruba\/wp-content\/uploads\/2022\/08\/Highlifeng.com_-100.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/highlifeng.com\/yoruba\/wp-json\/wp\/v2\/posts\/4951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/highlifeng.com\/yoruba\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/highlifeng.com\/yoruba\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/highlifeng.com\/yoruba\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/highlifeng.com\/yoruba\/wp-json\/wp\/v2\/comments?post=4951"}],"version-history":[{"count":1,"href":"https:\/\/highlifeng.com\/yoruba\/wp-json\/wp\/v2\/posts\/4951\/revisions"}],"predecessor-version":[{"id":4963,"href":"https:\/\/highlifeng.com\/yoruba\/wp-json\/wp\/v2\/posts\/4951\/revisions\/4963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/highlifeng.com\/yoruba\/wp-json\/wp\/v2\/media\/4962"}],"wp:attachment":[{"href":"https:\/\/highlifeng.com\/yoruba\/wp-json\/wp\/v2\/media?parent=4951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/highlifeng.com\/yoruba\/wp-json\/wp\/v2\/categories?post=4951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/highlifeng.com\/yoruba\/wp-json\/wp\/v2\/tags?post=4951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}